{"id":5052,"date":"2025-11-25T14:17:12","date_gmt":"2025-11-25T13:17:12","guid":{"rendered":"https:\/\/dogtastic.ch\/?page_id=5052"},"modified":"2026-03-30T14:21:52","modified_gmt":"2026-03-30T12:21:52","slug":"spazierdienst","status":"publish","type":"page","link":"https:\/\/dogtastic.ch\/en\/pension-salon\/spazierdienst\/","title":{"rendered":"Dog Walking Service"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5052\" class=\"elementor elementor-5052\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65c9f982 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"65c9f982\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3eb25d44\" data-id=\"3eb25d44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1012d elementor-widget elementor-widget-heading\" data-id=\"1012d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Entspannter Hundespaziergang<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c9423a5 elementor-widget elementor-widget-text-editor\" data-id=\"4c9423a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Professionell organisiert<\/strong><\/p><p><strong>Mehr Bewegung, soziale Kontakte und klare Abl\u00e4ufe \u2013 damit Ihr Hund ausgeglichen ist und Sie Ihren Alltag entspannt meistern k\u00f6nnen. Wir holen Ihren Hund ab, f\u00fchren ihn in einer kleinen, passenden Gruppe aus und bringen ihn wieder zur\u00fcck \u2013 zuverl\u00e4ssig und hundegerecht.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-42680dd0 elementor-hidden-phone\" data-id=\"42680dd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-d2bd5be e-flex e-con-boxed e-con e-parent\" data-id=\"d2bd5be\" data-element_type=\"container\" data-e-type=\"container\" id=\"dtws-01\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f1431e4 e-flex e-con-boxed e-con e-child\" data-id=\"f1431e4\" data-element_type=\"container\" data-e-type=\"container\" id=\"dtws-hero\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-564eae4 e-con-full e-flex e-con e-child\" data-id=\"564eae4\" data-element_type=\"container\" data-e-type=\"container\" id=\"dtws-wrap\">\n\t\t<div class=\"elementor-element elementor-element-7dc099d e-con-full dtws-ctaRow e-flex e-con e-child\" data-id=\"7dc099d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92518a6 dtws-btn elementor-widget elementor-widget-button\" data-id=\"92518a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#dtws-anfrage\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Unverbindlich Interesse anmelden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-791d14f dtws-btn dtws-btn--secondary elementor-widget elementor-widget-button\" data-id=\"791d14f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#dtws-preise\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Preise ansehen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8bea51c dtws-card e-flex e-con-boxed e-con e-child\" data-id=\"8bea51c\" data-element_type=\"container\" data-e-type=\"container\" id=\"dtws-warum\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5dc829 dtws-h2 elementor-widget elementor-widget-heading\" data-id=\"a5dc829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum der Spazierservice von Dogtastic?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72d3c7a dtws-p elementor-widget elementor-widget-text-editor\" data-id=\"72d3c7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ein guter Spaziergang ist mehr als Bewegung: Er bringt Ruhe, Ausgeglichenheit und sichere soziale Kontakte.<br \/>Wir organisieren die Spazierg\u00e4nge so, dass Hunde nicht \u00fcberfordert werden \u2013 und Sie sich auf einen klaren, verl\u00e4sslichen Ablauf verlassen k\u00f6nnen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc21312 e-grid e-con-full dtws-two e-con e-child\" data-id=\"bc21312\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d59669 dtws-kicker elementor-widget elementor-widget-heading\" data-id=\"8d59669\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">F\u00fcr Ihren Hund<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53e253f dtws-kicker elementor-widget elementor-widget-heading\" data-id=\"53e253f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">F\u00fcr Sie<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2575a3b dtws-ul elementor-widget elementor-widget-text-editor\" data-id=\"2575a3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>Regelm\u00e4ssige Bewegung in einer passenden Hundegruppe<\/li><li>Sozialkontakte ohne \u00dcberforderung \u2013 in kleinen, sorgf\u00e4ltig zusammengestellten Gruppen<\/li><li>Strukturierter Ablauf mit Ruhe und Klarheit<\/li><li>Sinnvolle Auslastung, die gut tut\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d4b556 dtws-ul elementor-widget elementor-widget-text-editor\" data-id=\"0d4b556\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>Entlastung im Arbeitsalltag \u2013 wenn die Zeit knapp ist<\/li><li>Unterst\u00fctzung bei eingeschr\u00e4nkter Mobilit\u00e4t (z. B. nach Unfall\/Krankheit)<\/li><li>Planbare, verl\u00e4ssliche Betreuung (Abholung &amp; R\u00fcckbringung inklusive)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7058915 dtws-noteBox dtws-mt12 elementor-widget elementor-widget-text-editor\" data-id=\"7058915\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Immer dann, wenn der Alltag weniger Raum f\u00fcr ausgedehnte Spazierg\u00e4nge oder soziale Kontakte bietet, sorgt unser Spazierservice f\u00fcr Bewegung, Abwechslung und kontrollierte Hundebegegnungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c4f09fe e-con-full dtws-card e-flex e-con e-child\" data-id=\"c4f09fe\" data-element_type=\"container\" data-e-type=\"container\" id=\"dtws-ablauf\">\n\t\t\t\t<div class=\"elementor-element elementor-element-517e82c dtws-h2 elementor-widget elementor-widget-heading\" data-id=\"517e82c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unser Spazierservice \u2013 so arbeiten wir<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45fe13a e-con-full dtws-step e-flex e-con e-child\" data-id=\"45fe13a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a2bbcc dtws-kicker elementor-widget elementor-widget-heading\" data-id=\"2a2bbcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Abholung (Dogtastic-Bus)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ce2d87 dtws-body elementor-widget elementor-widget-text-editor\" data-id=\"3ce2d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir holen Ihren Hund bei Ihnen zu Hause oder an einem vereinbarten Ort ab \u2013 mit einem speziell f\u00fcr Hunde ausgebauten Dogtastic Bus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74514c8 e-con-full dtws-step e-flex e-con e-child\" data-id=\"74514c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d7fe4c dtws-kicker elementor-widget elementor-widget-heading\" data-id=\"7d7fe4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Spaziergang in kleiner Gruppe<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9090381 dtws-body elementor-widget elementor-widget-text-editor\" data-id=\"9090381\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir f\u00fchren unsere Spazierg\u00e4nge bewusst in kleinen Gruppen von 3 bis maximal 5 Hunden\u00a0durch.<\/p><p>Hunde reagieren aufeinander \u2013 und auf ihre Umwelt. Ein pl\u00f6tzlich auftauchendes Reh, ein freilaufender Hund oder ein unerwarteter Reiz k\u00f6nnen eine Gruppe innert Sekunden in Bewegung versetzen.<\/p><p>Je gr\u00f6sser eine Gruppe wird, desto anspruchsvoller werden Dynamik und Kontrolle \u2013 und desto schwieriger wird es, den \u00dcberblick zu behalten.<\/p><p>Mit maximal f\u00fcnf Hunden kann eine Begleitperson jedes Tier im Blick behalten, fr\u00fchzeitig eingreifen und die Gruppe ruhig und souver\u00e4n f\u00fchren.<\/p><p>Gr\u00f6ssere Gruppen m\u00f6gen organisatorisch einfacher und kosteng\u00fcnstiger sein. F\u00fcr uns jedoch steht die Sicherheit der Hunde\u00a0an erster Stelle.<\/p><p>Qualit\u00e4t vor Quantit\u00e4t.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4194c62 e-con-full dtws-step e-flex e-con e-child\" data-id=\"4194c62\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fea97d6 elementor-widget elementor-widget-heading\" data-id=\"fea97d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">R\u00fcckbringung<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a5ec3d dtws-body elementor-widget elementor-widget-text-editor\" data-id=\"9a5ec3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nach dem Spaziergang bringen wir Ihren Hund entspannt wieder zur\u00fcck.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5914fe e-con-full dtws-step e-flex e-con e-child\" data-id=\"d5914fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ba411b elementor-widget elementor-widget-heading\" data-id=\"5ba411b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Dauer<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58afc0b dtws-body elementor-widget elementor-widget-text-editor\" data-id=\"58afc0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Der Spaziergang dauert in der Regel 50-60 Minuten (je nach Gruppe, Wetter und Situation).<br \/>Der gesamte Ablauf ist klar strukturiert und auf das Wohl der Hunde ausgerichtet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7dece4 dtws-card e-con-full e-flex e-con e-child\" data-id=\"f7dece4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-627e348 dtws-h2 elementor-widget elementor-widget-heading\" data-id=\"627e348\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F\u00fcr wen ist der Spazierservice geeignet?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c78a18 dtws-p elementor-widget elementor-widget-text-editor\" data-id=\"4c78a18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Unser Spazierservice eignet sich besonders f\u00fcr Hunde, die gerne draussen unterwegs sind, grunds\u00e4tzlich sozialvertr\u00e4glich sind und von klaren Strukturen profitieren \u2013 und f\u00fcr Halter:innen, die sich im Alltag Entlastung oder zus\u00e4tzliche Unterst\u00fctzung w\u00fcnschen.<\/p><p>Damit alle Hunde eine gute Zeit haben, lernen wir jeden Hund vorab pers\u00f6nlich\u00a0kennen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af047a7 e-con-full dtws-card e-flex e-con e-child\" data-id=\"af047a7\" data-element_type=\"container\" data-e-type=\"container\" id=\"dtws-kennenlernen\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d636101 dtws-h2 elementor-widget elementor-widget-heading\" data-id=\"d636101\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kennenlerntermin<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e108802 dtws-p elementor-widget elementor-widget-text-editor\" data-id=\"e108802\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Bevor Ihr Hund regelm\u00e4ssig am Spazierservice teilnimmt, f\u00fchren wir einen Kennenlerntermin durch.<\/p><ul><li>Wir lernen Ihren Hund pers\u00f6nlich kennen<\/li><li>Wir kl\u00e4ren, welche Gruppe gut passt<\/li><li>Wir beantworten Ihre Fragen<\/li><li>Wir schaffen eine gute Basis f\u00fcr eine entspannte Zusammenarbeit<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b672bed dtws-card e-flex e-con-boxed e-con e-child\" data-id=\"b672bed\" data-element_type=\"container\" data-e-type=\"container\" id=\"dtws-preise\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca843fe dtws-h2 elementor-widget elementor-widget-heading\" data-id=\"ca843fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Preise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfdb5ef elementor-widget elementor-widget-text-editor\" data-id=\"dfdb5ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"dtws-tableWrap\" tabindex=\"0\" role=\"region\" aria-label=\"Preise Tabelle\">\n<table class=\"dtws-table\" aria-label=\"Preise Spazierservice\">\n<thead>\n<tr>\n<th class=\"dtws-th\">Leistung<\/th>\n<th class=\"dtws-th\">Preis<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"dtws-tr\">\n<td class=\"dtws-td\">Kennenlerntermin *<\/td>\n<td class=\"dtws-td dtws-price\">CHF 35.\u2013<\/td>\n<\/tr>\n<tr class=\"dtws-tr\">\n<td class=\"dtws-td\">Einzelspaziergang (50\u201360 Minuten)<\/td>\n<td class=\"dtws-td dtws-price\">CHF 35.\u2013<\/td>\n<\/tr>\n<tr class=\"dtws-tr\">\n<td class=\"dtws-td\"><strong>5er-Abo<\/strong>\n<span class=\"dtws-small\">F\u00fcr Kund:innen, die unseren Spazierservice kennenlernen m\u00f6chten.<\/span><\/td>\n<td class=\"dtws-td dtws-price\">CHF 170.\u2013<\/td>\n<\/tr>\n<tr class=\"dtws-tr\">\n<td class=\"dtws-td\"><strong>10er-Abo<\/strong>\n<span class=\"dtws-small\">F\u00fcr Hunde, die regelm\u00e4ssig bei uns mitlaufen \u2013 und f\u00fcr Halter:innen, die im Alltag entlastet werden m\u00f6chten.<\/span><\/td>\n<td class=\"dtws-td dtws-price\">CHF 315.\u2013<\/td>\n<\/tr>\n<tr class=\"dtws-tr\">\n<td class=\"dtws-td\"><strong>20er-Abo<\/strong>\n<span class=\"dtws-small\">F\u00fcr eine langfristige Zusammenarbeit und maximale Planungssicherheit.<\/span><\/td>\n<td class=\"dtws-td dtws-price\">CHF 600.\u2013<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<small><b>* <\/b>Der Kennenlerntermin wird bei Abschluss eines Abos vollst\u00e4ndig angerechnet.<\/small>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2590e3 dtws-card e-flex e-con-boxed e-con e-child\" data-id=\"e2590e3\" data-element_type=\"container\" data-e-type=\"container\" id=\"dtws-qualitaet\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-212300b dtws-h2 elementor-widget elementor-widget-heading\" data-id=\"212300b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e4t &amp; Verantwortung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a519b4c dtws-p elementor-widget elementor-widget-text-editor\" data-id=\"a519b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Dogtastic ist keine private Gassi-L\u00f6sung, sondern ein professionell gef\u00fchrter Betrieb. Wir arbeiten mit klaren Abl\u00e4ufen statt Improvisation \u2013 und behalten dabei die Hundeliebe immer im Blick.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36e9b5a e-con-full dtws-two e-grid e-con e-child\" data-id=\"36e9b5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb43356 dtws-ul elementor-widget elementor-widget-text-editor\" data-id=\"cb43356\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>Fachlich ausgebildetes Team<\/li><li>Langj\u00e4hrige Erfahrung mit Gruppenbetreuung<\/li><li>Klare Abl\u00e4ufe statt Improvisation<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92207c5 dtws-ul elementor-widget elementor-widget-text-editor\" data-id=\"92207c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>R\u00fccksicht auf individuelle Bed\u00fcrfnisse<\/li><li>Tierwohl steht immer an erster Stelle<\/li><li>Sichere, passende Gruppenzusammenstellung<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8cd483 dtws-kicker dtws-mt12 elementor-widget elementor-widget-text-editor\" data-id=\"f8cd483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Unser Anspruch<br \/>Ein guter Spaziergang ist mehr als Bewegung \u2013 er schafft Ausgeglichenheit, Sicherheit und Vertrauen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bca209a dtws-card e-con-full e-flex e-con e-child\" data-id=\"bca209a\" data-element_type=\"container\" data-e-type=\"container\" id=\"dtws-faq\">\n\t\t\t\t<div class=\"elementor-element elementor-element-224e25e dtws-h2 elementor-widget elementor-widget-heading\" data-id=\"224e25e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5d724a elementor-widget elementor-widget-n-accordion\" data-id=\"f5d724a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;multiple&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2570\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2570\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Wie viele Hunde sind gleichzeitig unterwegs? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2570\" class=\"elementor-element elementor-element-3fbbb13 e-con-full e-flex e-con e-child\" data-id=\"3fbbb13\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2570\" class=\"elementor-element elementor-element-9d6c2e7 e-flex e-con-boxed e-con e-child\" data-id=\"9d6c2e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3065d1a elementor-widget elementor-widget-text-editor\" data-id=\"3065d1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir f\u00fchren Gruppen von 3 bis maximal 5 Hunden. So bleiben die Gruppen \u00fcberschaubar, sicher und hundegerecht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2571\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2571\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> An welchen Tagen findet der Spazierservice statt? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2571\" class=\"elementor-element elementor-element-19760bd e-con-full e-flex e-con e-child\" data-id=\"19760bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2571\" class=\"elementor-element elementor-element-dbe0290 e-flex e-con-boxed e-con e-child\" data-id=\"dbe0290\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db1d8d5 elementor-widget elementor-widget-text-editor\" data-id=\"db1d8d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Der Spazierservice findet werktags (Montag bis Freitag) statt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2572\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2572\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Wie l\u00e4uft die Abholung ab? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2572\" class=\"elementor-element elementor-element-acd2a6b e-con-full e-flex e-con e-child\" data-id=\"acd2a6b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2572\" class=\"elementor-element elementor-element-e9f51a2 e-flex e-con-boxed e-con e-child\" data-id=\"e9f51a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e472ef elementor-widget elementor-widget-text-editor\" data-id=\"3e472ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Wir holen Ihren Hund im vereinbarten Zeitfenster mit unserem speziell ausgebauten Dogtastic-Bus bei Ihnen zu Hause ab und bringen ihn nach dem Spaziergang wieder sicher zur\u00fcck.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2573\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2573\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Gibt es einen Kennenlern- oder Probespaziergang? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2573\" class=\"elementor-element elementor-element-cabab96 e-flex e-con-boxed e-con e-child\" data-id=\"cabab96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4689108 elementor-widget elementor-widget-text-editor\" data-id=\"4689108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Ja. Vor dem fixen Einstieg f\u00fchren wir einen Kennenlern-Spaziergang durch. Dieser kostet CHF 35.\u2013 und wird bei Abschluss eines Abonnements vollst\u00e4ndig gutgeschrieben. So stellen wir sicher, dass sich Ihr Hund wohlf\u00fchlt und gut in die Gruppe passt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2574\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2574\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Muss mein Hund bestimmte Voraussetzungen erf\u00fcllen? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2574\" class=\"elementor-element elementor-element-034bf47 e-flex e-con-boxed e-con e-child\" data-id=\"034bf47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0e3a39 elementor-widget elementor-widget-text-editor\" data-id=\"f0e3a39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Der Spazierservice richtet sich prim\u00e4r an sozial vertr\u00e4gliche Hunde, die sich in einer kleinen Gruppe wohlf\u00fchlen. Ob ein Hund geeignet ist, beurteilen wir individuell beim Kennenlernen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2575\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2575\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Was passiert, wenn mein Hund nicht in eine Gruppe passt? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2575\" class=\"elementor-element elementor-element-2ef3411 e-flex e-con-boxed e-con e-child\" data-id=\"2ef3411\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-159fdea elementor-widget elementor-widget-text-editor\" data-id=\"159fdea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Dann suchen wir gemeinsam nach einer passenden L\u00f6sung oder empfehlen eine andere Betreuungsform. Wichtig ist, dass es f\u00fcr Ihren Hund und f\u00fcr die Gruppe stimmig ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2576\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2576\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Was passiert, wenn f\u00fcr meinen Wunschtag noch keine Gruppe besteht? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2576\" class=\"elementor-element elementor-element-37ed0d8 e-flex e-con-boxed e-con e-child\" data-id=\"37ed0d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-177e1d3 elementor-widget elementor-widget-text-editor\" data-id=\"177e1d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">In diesem Fall setzen wir Ihren Hund auf die Warteliste. Sobald f\u00fcr den gew\u00fcnschten Tag mindestens drei passende Hunde zusammen sind, nehmen wir mit Ihnen Kontakt auf und starten den Spazierservice.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2577\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2577\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Wie lange ist ein Abonnement g\u00fcltig? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2577\" class=\"elementor-element elementor-element-8ebeb4d e-flex e-con-boxed e-con e-child\" data-id=\"8ebeb4d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27d4aae elementor-widget elementor-widget-text-editor\" data-id=\"27d4aae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Unsere Abonnemente sind zeitlich flexibel g\u00fcltig und nicht an ein fixes Ablaufdatum gebunden. Nicht genutzte Spazierg\u00e4nge verfallen nicht und k\u00f6nnen nach Absprache sp\u00e4ter bezogen werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2578\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"9\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2578\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Was passiert bei schlechtem Wetter? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2578\" class=\"elementor-element elementor-element-f3d803f e-flex e-con-boxed e-con e-child\" data-id=\"f3d803f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fdf74d elementor-widget elementor-widget-text-editor\" data-id=\"1fdf74d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Der Spazierservice findet grunds\u00e4tzlich auch bei Regen statt. Bei extremen Wetterbedingungen passen wir Dauer und Ablauf an oder setzen eine Runde aus \u2013 immer im Sinne der Sicherheit und des Wohlbefindens der Hunde.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ac8e6c dtws-card e-flex e-con-boxed e-con e-child\" data-id=\"2ac8e6c\" data-element_type=\"container\" data-e-type=\"container\" id=\"dtws-anfrage\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6dd5956 dtws-h2 elementor-widget elementor-widget-heading\" data-id=\"6dd5956\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unverbindlich Interesse anmelden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48b8d92 dtws-p elementor-widget elementor-widget-text-editor\" data-id=\"48b8d92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>M\u00f6chten Sie mehr \u00fcber unseren Spazierservice erfahren oder pr\u00fcfen, ob er zu Ihrem Hund passt?<br \/>Gerne melden wir uns unverbindlich bei Ihnen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2829a01a elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"2829a01a\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"gassiform\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"5052\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"2829a01a\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Spazierservice - Dogtastic\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"5052\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-sf_name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[sf_name]\" id=\"form-field-sf_name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_f63a723 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f63a723\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tStrasse\/Nr\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_f63a723]\" id=\"form-field-field_f63a723\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Strasse\/Nr\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-sf_zipcity elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_zipcity\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPLZ\/Ort\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[sf_zipcity]\" id=\"form-field-sf_zipcity\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"PLZ\/Ort\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-sf_tel elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_tel\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefon\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[sf_tel]\" id=\"form-field-sf_tel\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefon\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Seuls les caract\u00e8res de num\u00e9ros de t\u00e9l\u00e9phone (#, -, *, etc.) sont accept\u00e9s.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-sf_mail elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_mail\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[sf_mail]\" id=\"form-field-sf_mail\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-sf_days elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_days\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tWunschtage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  elementor-subgroup-inline\"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"MO\" id=\"form-field-sf_days-0\" name=\"form_fields[sf_days][]\"> <label for=\"form-field-sf_days-0\">MO<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"DI\" id=\"form-field-sf_days-1\" name=\"form_fields[sf_days][]\"> <label for=\"form-field-sf_days-1\">DI<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"MI\" id=\"form-field-sf_days-2\" name=\"form_fields[sf_days][]\"> <label for=\"form-field-sf_days-2\">MI<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"DO\" id=\"form-field-sf_days-3\" name=\"form_fields[sf_days][]\"> <label for=\"form-field-sf_days-3\">DO<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"FR\" id=\"form-field-sf_days-4\" name=\"form_fields[sf_days][]\"> <label for=\"form-field-sf_days-4\">FR<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-field_da69ba3 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_da69ba3\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTageszeit\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  elementor-subgroup-inline\"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Morgen\" id=\"form-field-field_da69ba3-0\" name=\"form_fields[field_da69ba3][]\"> <label for=\"form-field-field_da69ba3-0\">Morgen<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Mittag\" id=\"form-field-field_da69ba3-1\" name=\"form_fields[field_da69ba3][]\"> <label for=\"form-field-field_da69ba3-1\">Mittag<\/label><\/span><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Nachmittag\" id=\"form-field-field_da69ba3-2\" name=\"form_fields[field_da69ba3][]\"> <label for=\"form-field-field_da69ba3-2\">Nachmittag<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-date elementor-field-group elementor-column elementor-field-group-sf_start elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_start\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tStartzeitraum\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\n\t\t<input type=\"date\" name=\"form_fields[sf_start]\" id=\"form-field-sf_start\" class=\"elementor-field elementor-size-sm  elementor-field-textual elementor-date-field\" placeholder=\"Startzeitraum\" required=\"required\" pattern=\"[0-9]{4}-[0-9]{2}-[0-9]{2}\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-sf_dogname elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_dogname\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tName Hund\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[sf_dogname]\" id=\"form-field-sf_dogname\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name Hund\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-number elementor-field-group elementor-column elementor-field-group-sf_dogage elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_dogage\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tAlter Hund\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t<input type=\"number\" name=\"form_fields[sf_dogage]\" id=\"form-field-sf_dogage\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Alter Hund\" required=\"required\" min=\"\" max=\"\" >\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-sf_vertraeglichkeit elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_vertraeglichkeit\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tSozialvertr\u00e4glichkeit\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[sf_vertraeglichkeit]\" id=\"form-field-sf_vertraeglichkeit\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"-\">-<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ja\">Ja<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Meistens\">Meistens<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Unsicher\">Unsicher<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-sf_bemerkungen elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_bemerkungen\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tBemerkungen\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[sf_bemerkungen]\" id=\"form-field-sf_bemerkungen\" rows=\"4\" placeholder=\"Erz\u00e4hlen Sie uns etwas \u00fcber Ihren Hund\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-sf_accept elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-sf_accept\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tDatenschutzerkl\u00e4rung\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[sf_accept]\" id=\"form-field-sf_accept\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-sf_accept\">Ich akzeptiere die <a href=\"https:\/\/dogtastic.ch\/datenschutz\/\" target=\"_blank\">Datenschutzerkl\u00e4rung<\/a><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_64ac10c elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_64ac10c\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LcZbWAsAAAAAOasqMPtFIEFXESmCuEKgv3-mXex\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Senden<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d40d21d elementor-widget elementor-widget-html\" data-id=\"d40d21d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<script>\n(function(){\n  const input = document.querySelector('#gassiform #form-field-sf_start');\n  if(!input) return;\n\n  function normalizeToDDMMYYYY(val){\n    if(!val) return val;\n\n    \/\/ schon korrekt: 12.09.1978\n    if (\/^\\d{2}\\.\\d{2}\\.\\d{4}$\/.test(val)) return val;\n\n    \/\/ ISO: 1978-09-12 oder 1978\/09\/12\n    const m1 = val.match(\/^(\\d{4})[-\\\/](\\d{2})[-\\\/](\\d{2})$\/);\n    if (m1) return `${m1[3]}.${m1[2]}.${m1[1]}`;\n\n    \/\/ falls der Picker mal 12-09-1978 oder 12\/09\/1978 liefert\n    const m2 = val.match(\/^(\\d{2})[-\\\/](\\d{2})[-\\\/](\\d{4})$\/);\n    if (m2) return `${m2[1]}.${m2[2]}.${m2[3]}`;\n\n    return val; \/\/ unbekannt -> nicht anfassen\n  }\n\n  function apply(){\n    input.value = normalizeToDDMMYYYY(input.value);\n  }\n\n  \/\/ reagiert auf Picker + manuelle Eingabe\n  ['change','input','blur'].forEach(evt => input.addEventListener(evt, apply, true));\n\n  \/\/ falls beim Laden schon ein Wert drin ist\n  apply();\n})();\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-737c353 elementor-widget elementor-widget-html\" data-id=\"737c353\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<script>\n(function(){\n  const fieldSel = '#gassiform #form-field-sf_start';\n\n  function killPattern(){\n    const el = document.querySelector(fieldSel);\n    if (!el) return;\n\n    \/\/ Pattern killen (das ist der Grund fuer die Fehlermeldung)\n    el.removeAttribute('pattern');\n\n    \/\/ optional: manche Browser merken sich eine Validity-Meldung\n    if (typeof el.setCustomValidity === 'function') el.setCustomValidity('');\n  }\n\n  \/\/ sofort + nachladen\n  if (document.readyState === 'loading') {\n    document.addEventListener('DOMContentLoaded', killPattern);\n  } else {\n    killPattern();\n  }\n\n  \/\/ falls Elementor das pattern spaeter wieder setzt: beobachten und erneut entfernen\n  const obs = new MutationObserver(() => killPattern());\n  obs.observe(document.documentElement, { attributes: true, subtree: true, attributeFilter: ['pattern'] });\n\n})();\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Entspannter Hundespaziergang Professionell organisiert Mehr Bewegung, soziale Kontakte und klare Abl\u00e4ufe \u2013 damit Ihr Hund ausgeglichen ist und Sie Ihren Alltag entspannt meistern k\u00f6nnen. Wir holen Ihren Hund ab, f\u00fchren ihn in einer kleinen, passenden Gruppe aus und bringen ihn wieder zur\u00fcck \u2013 zuverl\u00e4ssig und hundegerecht. Unverbindlich Interesse anmelden Preise ansehen Warum der Spazierservice von [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":2576,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5052","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spazierservice - Dogtastic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dogtastic.ch\/en\/pension-salon\/spazierdienst\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spazierservice - Dogtastic\" \/>\n<meta property=\"og:description\" content=\"Entspannter Hundespaziergang Professionell organisiert Mehr Bewegung, soziale Kontakte und klare Abl\u00e4ufe \u2013 damit Ihr Hund ausgeglichen ist und Sie Ihren Alltag entspannt meistern k\u00f6nnen. Wir holen Ihren Hund ab, f\u00fchren ihn in einer kleinen, passenden Gruppe aus und bringen ihn wieder zur\u00fcck \u2013 zuverl\u00e4ssig und hundegerecht. Unverbindlich Interesse anmelden Preise ansehen Warum der Spazierservice von [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dogtastic.ch\/en\/pension-salon\/spazierdienst\/\" \/>\n<meta property=\"og:site_name\" content=\"Dogtastic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dogtastic.ch\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T12:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dogtastic.ch\/wp-content\/uploads\/2025\/04\/dogtastic-hunde-Tagesbetreuung-44.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dogtastic.ch\\\/pension-salon\\\/spazierdienst\\\/\",\"url\":\"https:\\\/\\\/dogtastic.ch\\\/pension-salon\\\/spazierdienst\\\/\",\"name\":\"Spazierservice - Dogtastic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dogtastic.ch\\\/#website\"},\"datePublished\":\"2025-11-25T13:17:12+00:00\",\"dateModified\":\"2026-03-30T12:21:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dogtastic.ch\\\/pension-salon\\\/spazierdienst\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dogtastic.ch\\\/pension-salon\\\/spazierdienst\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dogtastic.ch\\\/pension-salon\\\/spazierdienst\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dogtastic.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1. Pension + Spazierservice\",\"item\":\"https:\\\/\\\/dogtastic.ch\\\/pension-salon\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Spazierservice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dogtastic.ch\\\/#website\",\"url\":\"https:\\\/\\\/dogtastic.ch\\\/\",\"name\":\"Dogtastic\",\"description\":\"Tages- und Ferienpl\u00e4tze f\u00fcr Hunde\",\"publisher\":{\"@id\":\"https:\\\/\\\/dogtastic.ch\\\/#organization\"},\"alternateName\":\"Tages- & Ferienpl\u00e4tze f\u00fcr Hunde & Hundesalon in Grandsivaz - Montagny\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dogtastic.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dogtastic.ch\\\/#organization\",\"name\":\"Dogtastic\",\"url\":\"https:\\\/\\\/dogtastic.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dogtastic.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dogtastic.ch\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Dogtastic-dark-768x408-1.png\",\"contentUrl\":\"https:\\\/\\\/dogtastic.ch\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Dogtastic-dark-768x408-1.png\",\"width\":768,\"height\":408,\"caption\":\"Dogtastic\"},\"image\":{\"@id\":\"https:\\\/\\\/dogtastic.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dogtastic.ch\",\"https:\\\/\\\/www.instagram.com\\\/dogtastic.ch\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spazierservice - Dogtastic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dogtastic.ch\/en\/pension-salon\/spazierdienst\/","og_locale":"en_US","og_type":"article","og_title":"Spazierservice - Dogtastic","og_description":"Entspannter Hundespaziergang Professionell organisiert Mehr Bewegung, soziale Kontakte und klare Abl\u00e4ufe \u2013 damit Ihr Hund ausgeglichen ist und Sie Ihren Alltag entspannt meistern k\u00f6nnen. Wir holen Ihren Hund ab, f\u00fchren ihn in einer kleinen, passenden Gruppe aus und bringen ihn wieder zur\u00fcck \u2013 zuverl\u00e4ssig und hundegerecht. Unverbindlich Interesse anmelden Preise ansehen Warum der Spazierservice von [&hellip;]","og_url":"https:\/\/dogtastic.ch\/en\/pension-salon\/spazierdienst\/","og_site_name":"Dogtastic","article_publisher":"https:\/\/www.facebook.com\/dogtastic.ch","article_modified_time":"2026-03-30T12:21:52+00:00","og_image":[{"width":1440,"height":1920,"url":"https:\/\/dogtastic.ch\/wp-content\/uploads\/2025\/04\/dogtastic-hunde-Tagesbetreuung-44.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dogtastic.ch\/pension-salon\/spazierdienst\/","url":"https:\/\/dogtastic.ch\/pension-salon\/spazierdienst\/","name":"Spazierservice - Dogtastic","isPartOf":{"@id":"https:\/\/dogtastic.ch\/#website"},"datePublished":"2025-11-25T13:17:12+00:00","dateModified":"2026-03-30T12:21:52+00:00","breadcrumb":{"@id":"https:\/\/dogtastic.ch\/pension-salon\/spazierdienst\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dogtastic.ch\/pension-salon\/spazierdienst\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dogtastic.ch\/pension-salon\/spazierdienst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dogtastic.ch\/"},{"@type":"ListItem","position":2,"name":"1. Pension + Spazierservice","item":"https:\/\/dogtastic.ch\/pension-salon\/"},{"@type":"ListItem","position":3,"name":"Spazierservice"}]},{"@type":"WebSite","@id":"https:\/\/dogtastic.ch\/#website","url":"https:\/\/dogtastic.ch\/","name":"Dogtastic","description":"Day care and boarding for dogs","publisher":{"@id":"https:\/\/dogtastic.ch\/#organization"},"alternateName":"Tages- & Ferienpl\u00e4tze f\u00fcr Hunde & Hundesalon in Grandsivaz - Montagny","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dogtastic.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dogtastic.ch\/#organization","name":"Dogtastic","url":"https:\/\/dogtastic.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dogtastic.ch\/#\/schema\/logo\/image\/","url":"https:\/\/dogtastic.ch\/wp-content\/uploads\/2025\/04\/Dogtastic-dark-768x408-1.png","contentUrl":"https:\/\/dogtastic.ch\/wp-content\/uploads\/2025\/04\/Dogtastic-dark-768x408-1.png","width":768,"height":408,"caption":"Dogtastic"},"image":{"@id":"https:\/\/dogtastic.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dogtastic.ch","https:\/\/www.instagram.com\/dogtastic.ch\/"]}]}},"_links":{"self":[{"href":"https:\/\/dogtastic.ch\/en\/wp-json\/wp\/v2\/pages\/5052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dogtastic.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dogtastic.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dogtastic.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dogtastic.ch\/en\/wp-json\/wp\/v2\/comments?post=5052"}],"version-history":[{"count":229,"href":"https:\/\/dogtastic.ch\/en\/wp-json\/wp\/v2\/pages\/5052\/revisions"}],"predecessor-version":[{"id":5682,"href":"https:\/\/dogtastic.ch\/en\/wp-json\/wp\/v2\/pages\/5052\/revisions\/5682"}],"up":[{"embeddable":true,"href":"https:\/\/dogtastic.ch\/en\/wp-json\/wp\/v2\/pages\/2576"}],"wp:attachment":[{"href":"https:\/\/dogtastic.ch\/en\/wp-json\/wp\/v2\/media?parent=5052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}